{"id":2610,"date":"2024-05-03T16:15:07","date_gmt":"2024-05-03T14:15:07","guid":{"rendered":"https:\/\/www.sealines.eu\/?p=2610"},"modified":"2024-05-03T17:05:42","modified_gmt":"2024-05-03T15:05:42","slug":"proroga-early-booking-ventouris-ferries-sconto-del-25","status":"publish","type":"post","link":"https:\/\/www.sealines.eu\/el\/novita-e-promozioni\/proroga-early-booking-ventouris-ferries-sconto-del-25\/","title":{"rendered":"PROROGA EARLY BOOKING VENTOURIS FERRIES &#8211; SCONTO DEL 25%"},"content":{"rendered":"<h3><span style=\"color: #ff0000;\"><strong style=\"color: #165eac; font-family: tahoma, arial, helvetica, sans-serif; font-size: 1.2em;\">L&#8217;ESTATE SI AVVICINA!<br \/>\nPENSATI AL MARE!\u00a0<\/strong><\/span><\/h3>\n<p>Sconto del 25% per biglietti fino al 15\/05\/2024. I biglietti emessi con questa offerta non sono rimborsabili. Disponibilit\u00e0 limitata.<\/p>\n<p><span style=\"font-size: 16pt; color: #165eac;\"><a style=\"color: #165eac;\" href=\"https:\/\/www.sealines.eu\/el\/bari-corfu\/\"><span style=\"color: #165eac; font-size: 18pt;\">- \u039c\u03c0\u03ac\u03c1\u03b9 - \u039a\u03ad\u03c1\u03ba\u03c5\u03c1\u03b1<\/span><\/a><\/span><\/p>\n<p><a href=\"https:\/\/www.sealines.eu\/el\/bari-igoumenitsa\/\"><span style=\"color: #165eac; font-size: 18pt;\">- \u039c\u03c0\u03ac\u03c1\u03b9 - \u0397\u03b3\u03bf\u03c5\u03bc\u03b5\u03bd\u03af\u03c4\u03c3\u03b1\u00a0<\/span><\/a><\/p>\n<p><a href=\"https:\/\/www.sealines.eu\/el\/bari-cefalonia\/\"><span style=\"color: #165eac; font-size: 18pt;\">- \u039c\u03c0\u03ac\u03c1\u03b9 - \u039a\u03b5\u03c6\u03b1\u03bb\u03bf\u03bd\u03b9\u03ac\u00a0<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>PROROGA EARLY BOOKING ESTATE 2024<\/p>\n<p>Sconto del 25% per acquisti dei biglietti trahetto fino al 15\/05\/2024. I biglietti emessi con questa offerta non sono rimborsabili. La disponibilit\u00e0 \u00e8 limitata.<\/p>\n<p>Ma affrettati. Conviene acquistare in anticipo il biglietto del traghetto, non solo per aggiudicarsi l&#8217;offerta migliore, ma anche per assicurarsi una buona sistemazione per tutta la famiglia. Emesso il biglietto e prenotato l&#8217;albergo o l&#8217;appartamento, potrai dedicarti con cura alla scelta delle spiagge pi\u00f9 belle e all&#8217;organizzazione di escursioni e visite per una vacanza indimenticabile.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2626\" src=\"https:\/\/www.sealines.eu\/wp-content\/uploads\/2024\/05\/ventouris-ferries-sconto-traghetti-naxos-aliko-hawaii-beach-150x150.webp\" alt=\"\" width=\"200\" height=\"140\" srcset=\"https:\/\/www.sealines.eu\/wp-content\/uploads\/2024\/05\/ventouris-ferries-sconto-traghetti-naxos-aliko-hawaii-beach-300x210.webp 300w, https:\/\/www.sealines.eu\/wp-content\/uploads\/2024\/05\/ventouris-ferries-sconto-traghetti-naxos-aliko-hawaii-beach-768x537.webp 768w, https:\/\/www.sealines.eu\/wp-content\/uploads\/2024\/05\/ventouris-ferries-sconto-traghetti-naxos-aliko-hawaii-beach.webp 830w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" data-no-auto-translation=\"\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2627\" src=\"https:\/\/www.sealines.eu\/wp-content\/uploads\/2024\/05\/ventouris-ferries-sconto-traghetti-cucina-greca-2024-150x150.webp\" alt=\"\" width=\"210\" height=\"140\" srcset=\"https:\/\/www.sealines.eu\/wp-content\/uploads\/2024\/05\/ventouris-ferries-sconto-traghetti-cucina-greca-2024-300x200.webp 300w, https:\/\/www.sealines.eu\/wp-content\/uploads\/2024\/05\/ventouris-ferries-sconto-traghetti-cucina-greca-2024.webp 720w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" data-no-auto-translation=\"\" \/><\/p>\n<p>La Grecia \u00e8 ricca di posti incantevoli, di spiagge meravigliose e siti archeologici di grande interesse storico e culturale, di isole dalla natura incontaminata e bellezza imperdibile scelte da molti come destinazioni preferite di viaggio per l&#8217;estate, ma anche da percorsi eno-gastronomici vari dai sapori tradizionali, all&#8217;insegna della convivialit\u00e0.<\/p>\n<p>Prenota la tua vacanza estiva a prezzi scontati! Scegli la tratta del tuo viaggio in traghetto per la Grecia, consulta orari, tariffe e promozioni in corso, verifica la disponibilit\u00e0 e acquista il tuo biglietto direttamente dal nostro Portale Traghetti. Se hai bisogno di informazioni, non esitare a contattarci! Il nostro Centro Prenotazioni Traghetti Grecia \u00e8 continuamente aggiornato sulle novit\u00e0 e sulle offerte della Compagnia VENTOURIS FERRIES. Invia una mail a booking@sealines.eu oppure chiama il numero 0809260042. Puoi ottenere informazioni su offerte e novit\u00e0 anche seguendo i nostri canali social e tramite whatsapp, viber o telegram. Basta aggiungere alla tua rubrica il numero 3441743399 (attivo dal lunedi al venerdi dalle 9:00 alle 19:00 e sabato dalle 09:00 alle 13:00). Il nostro staff sar\u00e0 lieto di poterti aiutare.<\/p>","protected":false},"excerpt":{"rendered":"<p>L&#8217;ESTATE SI AVVICINA! PENSATI AL MARE!\u00a0 Sconto del 25% per biglietti fino al 15\/05\/2024. I biglietti emessi con questa offerta non sono rimborsabili. Disponibilit\u00e0 limitata. &#8211; Bari &#8211; Corfu &#8211; Bari &#8211; Igoumenitsa\u00a0 &#8211; Bari &#8211; Cefalonia\u00a0 &nbsp; PROROGA EARLY BOOKING ESTATE 2024 Sconto del 25% per acquisti dei biglietti trahetto fino al 15\/05\/2024. I [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2636,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wds_primary_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novita-e-promozioni"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sealines.eu\/el\/wp-json\/wp\/v2\/posts\/2610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sealines.eu\/el\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sealines.eu\/el\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sealines.eu\/el\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sealines.eu\/el\/wp-json\/wp\/v2\/comments?post=2610"}],"version-history":[{"count":11,"href":"https:\/\/www.sealines.eu\/el\/wp-json\/wp\/v2\/posts\/2610\/revisions"}],"predecessor-version":[{"id":2637,"href":"https:\/\/www.sealines.eu\/el\/wp-json\/wp\/v2\/posts\/2610\/revisions\/2637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sealines.eu\/el\/wp-json\/wp\/v2\/media\/2636"}],"wp:attachment":[{"href":"https:\/\/www.sealines.eu\/el\/wp-json\/wp\/v2\/media?parent=2610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sealines.eu\/el\/wp-json\/wp\/v2\/categories?post=2610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sealines.eu\/el\/wp-json\/wp\/v2\/tags?post=2610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}